{"id":1536,"date":"2018-01-02T12:05:52","date_gmt":"2018-01-02T10:05:52","guid":{"rendered":"https:\/\/frdelpino.es\/try\/actualidad\/?p=1536"},"modified":"2023-12-29T12:14:39","modified_gmt":"2023-12-29T10:14:39","slug":"auge-populismo-revolucion","status":"publish","type":"post","link":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/","title":{"rendered":"La cuarta revoluci\u00f3n: el Estado"},"content":{"rendered":"<p style=\"text-align: justify;\">Uno de los denominadores comunes del auge del populismo en los pa\u00edses occidentales es la existencia de unos electores que est\u00e1n furiosos con la clase pol\u00edtica de sus respectivos pa\u00edses. Ese enfado es el que llev\u00f3 a Syriza al poder en Grecia, a Donald Trump a la presidencia de Estados Unidos o al radical Jeremy Corbyn al frente del Partido Laborista. Ese enfado explica, tambi\u00e9n, el auge del Frente Nacional en Francia, de Alternativa por Alemania o de Podemos en Espa\u00f1a.<\/p>\n<p style=\"text-align: justify;\">Esta tendencia, que se extiende por el mundo desarrollado, es un hecho de sobra conocido, pero \u00bfpor qu\u00e9 se produce ahora y no antes? <strong><span style=\"color: #008080;\">Adrian Wooldridge<\/span><\/strong>, editor del semanario <em>The Economist,<\/em> en el que escribe la columna <em>Schumpeter,<\/em> ofrece una respuesta que se aleja de los argumentos habituales relacionados con la globalizaci\u00f3n o el cambio tecnol\u00f3gico. Para Wooldridge, la ra\u00edz del problema se encuentra en los fallos que tiene el gobierno, fallos que se podr\u00edan corregir si las \u00e9lites pol\u00edticas se dedicaran a pensar en c\u00f3mo se puede mejorar el gobierno, que es lo que no han hecho. Y como nadie se dedica a reflexionar sobre esta cuesti\u00f3n, el resultado no ha sido otro que la idea de que no se puede hacer nada para arreglar los males que aquejan al Estado. De ah\u00ed a que empiece a reinar entre los ciudadanos un sentimiento, cada vez m\u00e1s fuerte, de desapego hacia las instituciones tradicionales. Hay solo un paso, una distancia muy peque\u00f1a, que los l\u00edderes populistas han sabido aprovechar en su favor para hablar no de reformar el Estado, sino de destruir el sistema para construir otro nuevo que encarne las ideas del l\u00edder populista, como, por ejemplo, la xenofobia, el igualitarismo, el nacionalismo y el proteccionismo.<\/p>\n<figure style=\"width: 270px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.frdelpino.es\/wp-content\/gallery\/wooldridge_1\/adrian-wooldridge-w13.jpg\" alt=\"\" width=\"270\" height=\"180\" \/><figcaption class=\"wp-caption-text\">Adrian Wooldridge. DB.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El populismo, sin embargo, no tiene porqu\u00e9 ser el destino inexorable de las sociedades occidentales porque, afortunadamente, el problema de los fallos del gobierno tiene soluci\u00f3n. Y esta consiste en algo tan simple y sencillo como reinventar el Estado. Wooldridge denomina a este proceso \u201cla cuarta revoluci\u00f3n\u201d. Pero \u00bfpor qu\u00e9 la cuarta? Pues porque, como ense\u00f1a la historia, desde que el Estado moderno se cre\u00f3 en Europa, esta instituci\u00f3n ha estado reinvent\u00e1ndose constantemente. Ese proceso de invenci\u00f3n y reinvenci\u00f3n del Estado ha conocido \u201ctres revoluciones y media\u201d, en palabras de Wooldridge. As\u00ed es que la que habr\u00eda que acometer ahora ser\u00eda la cuarta.<\/p>\n<p style=\"text-align: justify;\">La primera de las revoluciones, que tuvo lugar en el siglo XVII, buscaba aportar seguridad f\u00edsica a los pa\u00edses europeos en un entorno de guerra constante. No hay que olvidar que al siglo XVII europeo se le conoce como el Siglo de Hierro porque las guerras, las enfermedades, el clima adverso, las malas cosechas, el hambre y las revueltas populares que trae consigo y las m\u00e1s diversas calamidades azotaron a Europa con especial virulencia en esa centuria. La soluci\u00f3n que encontraron los europeos para protegerse de los cruentos conflictos b\u00e9licos que conocieron y del rosario de males que arrastraron con ellos fue la creaci\u00f3n de los estados centralizados. El fil\u00f3sofo Thomas Hobbes lo consideraba como la \u00fanica respuesta a la maldad, la brutalidad y la brevedad de la vida humana y lo bautiz\u00f3 con el nombre de un monstruo b\u00edblico: Leviat\u00e1n. La invenci\u00f3n del estado centralizado fue un \u00e9xito, seg\u00fan Wooldridge, porque de la competencia entre los estados europeos naci\u00f3 un sistema de gobierno en constante mejora. Esa competencia fue una de las causas de que Occidente empezara a sacar ventaja a las dem\u00e1s regiones del planeta y convirti\u00f3 a Europa en el verdadero centro del poder mundial.<\/p>\n<p style=\"text-align: justify;\">La segunda revoluci\u00f3n tuvo lugar a finales del siglo XVIII y comienzos del XIX y ven\u00eda inspirada por el deseo de libertad. Aunque hay quien identifica ese cambio con la revoluci\u00f3n americana, o con la francesa, lo cierto es que la verdadera revoluci\u00f3n tuvo lugar en Gran Breta\u00f1a, en la \u00e9poca victoriana. Su objetivo era promover la libertad individual, para lo que resultaba necesario introducir la responsabilidad del Estado y acotar su capacidad de limitar y recortar dicha libertad. Los brit\u00e1nicos \u201ccopiaron\u201d de los chinos la idea de una funci\u00f3n p\u00fablica profesional y eficiente, en sustituci\u00f3n del sistema de reparto de rentas a la aristocracia que la caracterizaba hasta esos momentos. El fil\u00f3sofo John Stuart Mill, adem\u00e1s, defendi\u00f3 la idea de la necesidad de reducir la presencia del Estado y su tama\u00f1o y limitar su papel a una mejor provisi\u00f3n de servicios para la gente.<\/p>\n<p style=\"text-align: justify;\">La inspiraci\u00f3n de la tercera revoluci\u00f3n fue la compasi\u00f3n. Esta revoluci\u00f3n tiene lugar tras el final de la Segunda Guerra Mundial, como consecuencia de la experiencia traum\u00e1tica de la crisis generalizada producto de la Gran Depresi\u00f3n. Esa experiencia fue una de las principales causas del conflicto b\u00e9lico. Los liberales brit\u00e1nicos pensaron que era necesario invertir en la calidad de la poblaci\u00f3n, en su bienestar, por lo que resultaba necesario proveer a los ciudadanos de servicios como educaci\u00f3n, sanidad y pensiones. De esta forma naci\u00f3 el Estado del bienestar, o Estado benefactor, o Estado providencia.<\/p>\n<p style=\"text-align: justify;\">Este modelo, que surgi\u00f3 en Gran Breta\u00f1a, se fue extendiendo al resto de pa\u00edses occidentales. Al mismo tiempo, el Estado empez\u00f3 a crecer cada vez m\u00e1s, a asumir y desarrollar m\u00e1s competencias, con sus consiguientes aumentos del gasto p\u00fablico, debido a las demandas crecientes de servicios p\u00fablicos por parte de los ciudadanos y a las expectativas en este sentido, tambi\u00e9n crecientes, que fueron alimentando los pol\u00edticos con sus promesas. El modelo funcion\u00f3 bien durante un tiempo, pero luego gener\u00f3 situaciones de inflaci\u00f3n y de estancamiento econ\u00f3mico.<\/p>\n<p style=\"text-align: justify;\">La media revoluci\u00f3n fue el intento que llevaron a cabo Ronald Reagan y Margaret Thatcher en la d\u00e9cada de los 80 de reducir el tama\u00f1o del Estado, pero fue media revoluci\u00f3n porque solo lo consiguieron mientras estuvieron en el poder, explica Wooldridge. Luego llegaron los Bush, Blair o Brown y con ellos el gasto p\u00fablico volvi\u00f3 a crecer. Y no solo eso; tambi\u00e9n se produjo, paralelamente, un aumento de la regulaci\u00f3n, esto es, de la intervenci\u00f3n del Estado en la vida econ\u00f3mica.<\/p>\n<p style=\"text-align: justify;\">Este proceso desemboca en la necesidad de una cuarta revoluci\u00f3n, debido a dos tipos de causas. Por un lado, est\u00e1n las razones negativas. La primera de ellas es un gasto p\u00fablico muy elevado, que provoca que la gente se vuelva adicta al mismo y da lugar a situaciones permanentes de d\u00e9ficit presupuestario. La segunda es una demograf\u00eda adversa, en forma de envejecimiento de la poblaci\u00f3n, que disminuye el n\u00famero de personas que trabajan y aumenta tanto el n\u00famero de jubilados como el gasto p\u00fablico relacionado con ellos. Desde esta perspectiva, la situaci\u00f3n actual del modelo de Estado es insostenible.<\/p>\n<p style=\"text-align: justify;\">Pero tambi\u00e9n hay dos razones positivas para justificar esa cuarta revoluci\u00f3n. En primer lugar, se encuentra la revoluci\u00f3n tecnol\u00f3gica y sus consecuencias, con su capacidad de cambiar lo que hace el Estado. La aplicaci\u00f3n de las nuevas tecnolog\u00edas supone una revoluci\u00f3n en los servicios p\u00fablicos, que aumenta la eficiencia con que se ofrecen al ciudadano. La segunda es la competencia creciente de las econom\u00edas emergentes, que tambi\u00e9n tiene lugar en el \u00e1mbito de los modelos de Estado. En Asia est\u00e1n inventando nuevas formas de Estado para realizar la provisi\u00f3n de servicios p\u00fablicos. Esto provoca la aparici\u00f3n de nuevos competidores, pero con un sistema de valores distintos en el que la democracia y la libertad tienen poco o ning\u00fan peso.<\/p>\n<p style=\"text-align: justify;\">Estos elementos explican la necesidad de esa cuarta revoluci\u00f3n, de reformar el Estado para salvarlo. Para ello es preciso que la clase pol\u00edtica deje de hacer promesas y de generar expectativas dif\u00edciles de cumplir en relaci\u00f3n con el Estado, porque esas promesas incumplidas y esas expectativas insatisfechas son las que dan lugar al apoyo de los ciudadanos a las opciones populistas.<\/p>\n<p style=\"text-align: right;\"><strong><a href=\"https:\/\/www.frdelpino.es\/video\/la-cuarta-revolucion-la-carrera-global-para-reinventar-el-estado\/\">Acceda a la conferencia completa<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los denominadores comunes del auge del populismo en los pa\u00edses occidentales es la existencia de unos electores que est\u00e1n furiosos con la clase pol\u00edtica de sus respectivos pa\u00edses. Ese enfado es el que llev\u00f3 a Syriza al poder en Grecia, a Donald Trump a la presidencia de Estados Unidos o al radical Jeremy [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[92,93,37,47,59],"class_list":{"0":"post-1536","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sociopolitica","8":"tag-administracion-publica","9":"tag-estado-del-bienestar","10":"tag-gobierno","11":"tag-libertad","12":"tag-politica"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La cuarta revoluci\u00f3n: el Estado - FRP Gaceta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cuarta revoluci\u00f3n: el Estado - FRP Gaceta\" \/>\n<meta property=\"og:description\" content=\"Uno de los denominadores comunes del auge del populismo en los pa\u00edses occidentales es la existencia de unos electores que est\u00e1n furiosos con la clase pol\u00edtica de sus respectivos pa\u00edses. Ese enfado es el que llev\u00f3 a Syriza al poder en Grecia, a Donald Trump a la presidencia de Estados Unidos o al radical Jeremy [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/\" \/>\n<meta property=\"og:site_name\" content=\"FRP Gaceta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frdelpino\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-02T10:05:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-29T10:14:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/06\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlota Taboada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frdelpino\" \/>\n<meta name=\"twitter:site\" content=\"@frdelpino\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlota Taboada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/\"},\"author\":{\"name\":\"Carlota Taboada\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\"},\"headline\":\"La cuarta revoluci\u00f3n: el Estado\",\"datePublished\":\"2018-01-02T10:05:52+00:00\",\"dateModified\":\"2023-12-29T10:14:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/\"},\"wordCount\":1403,\"image\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg\",\"keywords\":[\"Administraci\u00f3n P\u00fablica\",\"Estado del bienestar\",\"gobierno\",\"libertad\",\"pol\u00edtica\"],\"articleSection\":[\"Sociopol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/\",\"name\":\"La cuarta revoluci\u00f3n: el Estado - FRP Gaceta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg\",\"datePublished\":\"2018-01-02T10:05:52+00:00\",\"dateModified\":\"2023-12-29T10:14:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg\",\"contentUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg\",\"width\":612,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/auge-populismo-revolucion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La cuarta revoluci\u00f3n: el Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\",\"name\":\"FRP Gaceta\",\"description\":\"Una iniciativa de la Fundaci\u00f3n Rafael del Pino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\",\"name\":\"Carlota Taboada\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/author\\\/ctaboada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cuarta revoluci\u00f3n: el Estado - FRP Gaceta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/","og_locale":"es_ES","og_type":"article","og_title":"La cuarta revoluci\u00f3n: el Estado - FRP Gaceta","og_description":"Uno de los denominadores comunes del auge del populismo en los pa\u00edses occidentales es la existencia de unos electores que est\u00e1n furiosos con la clase pol\u00edtica de sus respectivos pa\u00edses. Ese enfado es el que llev\u00f3 a Syriza al poder en Grecia, a Donald Trump a la presidencia de Estados Unidos o al radical Jeremy [&hellip;]","og_url":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/","og_site_name":"FRP Gaceta","article_publisher":"https:\/\/www.facebook.com\/frdelpino","article_published_time":"2018-01-02T10:05:52+00:00","article_modified_time":"2023-12-29T10:14:39+00:00","og_image":[{"width":612,"height":612,"url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/06\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg","type":"image\/jpeg"}],"author":"Carlota Taboada","twitter_card":"summary_large_image","twitter_creator":"@frdelpino","twitter_site":"@frdelpino","twitter_misc":{"Escrito por":"Carlota Taboada","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#article","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/"},"author":{"name":"Carlota Taboada","@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86"},"headline":"La cuarta revoluci\u00f3n: el Estado","datePublished":"2018-01-02T10:05:52+00:00","dateModified":"2023-12-29T10:14:39+00:00","mainEntityOfPage":{"@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/"},"wordCount":1403,"image":{"@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#primaryimage"},"thumbnailUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/06\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg","keywords":["Administraci\u00f3n P\u00fablica","Estado del bienestar","gobierno","libertad","pol\u00edtica"],"articleSection":["Sociopol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/","url":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/","name":"La cuarta revoluci\u00f3n: el Estado - FRP Gaceta","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#primaryimage"},"image":{"@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#primaryimage"},"thumbnailUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/06\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg","datePublished":"2018-01-02T10:05:52+00:00","dateModified":"2023-12-29T10:14:39+00:00","author":{"@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86"},"breadcrumb":{"@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#primaryimage","url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/06\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg","contentUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/06\/stock-photo-travel-multicolored-part-of-people-one-person-cropped-adventure-holding-colorful-ig-543523277979266587_1716802.jpg","width":612,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/frdelpino.es\/actualidad\/auge-populismo-revolucion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/frdelpino.es\/actualidad\/"},{"@type":"ListItem","position":2,"name":"La cuarta revoluci\u00f3n: el Estado"}]},{"@type":"WebSite","@id":"https:\/\/frdelpino.es\/actualidad\/#website","url":"https:\/\/frdelpino.es\/actualidad\/","name":"FRP Gaceta","description":"Una iniciativa de la Fundaci\u00f3n Rafael del Pino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frdelpino.es\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86","name":"Carlota Taboada","url":"https:\/\/frdelpino.es\/actualidad\/author\/ctaboada\/"}]}},"_links":{"self":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":6,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1536\/revisions"}],"predecessor-version":[{"id":4358,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1536\/revisions\/4358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/media\/1539"}],"wp:attachment":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/media?parent=1536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/categories?post=1536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/tags?post=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}