{"id":1590,"date":"2018-01-02T12:55:11","date_gmt":"2018-01-02T10:55:11","guid":{"rendered":"https:\/\/frdelpino.es\/try\/actualidad\/?p=1590"},"modified":"2023-12-29T12:14:11","modified_gmt":"2023-12-29T10:14:11","slug":"union-europea-crisis","status":"publish","type":"post","link":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/","title":{"rendered":"La Uni\u00f3n Europea en entredicho"},"content":{"rendered":"<p style=\"text-align: justify;\">La Uni\u00f3n Europea no pasa, precisamente, por los mejores momentos de su historia. Aquellos momentos de euforia que se vivieron cuando se puso en marcha el euro, la UE se ampli\u00f3 a los pa\u00edses del este y se trabajaba por un proyecto de constituci\u00f3n europea, hoy han quedado atr\u00e1s y han dado paso a un tiempo marcado por el pesimismo y el sentimiento derrotista. \u00bfQu\u00e9 es lo que ha cambiado desde entonces? \u00bfQu\u00e9 es lo que ha ido mal para que los tonos brillantes de ayer se hayan transformado en la gama de grises de hoy?<\/p>\n<p style=\"text-align: justify;\">Cuando <span style=\"color: #008080;\"><strong>Loukas Tsoukalis<\/strong><\/span>, Pierre Keller Visiting Professor en la Harvard Kennedy School, trata de responder a estas cuestiones encuentra dos razones fundamentales: por un lado, la crisis de la uni\u00f3n monetaria europea, que ha mostrado la cara menos amable del euro; por otro, el problema de los refugiados y los inmigrantes, que ha abierto serias divisiones entre los distintos pa\u00edses europeos.<\/p>\n<p style=\"text-align: justify;\">La crisis del euro fue una pura cuesti\u00f3n de mala suerte porque la primera prueba de fuego para la moneda \u00fanica europea lleg\u00f3 de la mano de la crisis financiera internacional. La respuesta que la Uni\u00f3n Europea dio a la misma evidenci\u00f3 las profundas divisiones internas que subsisten en la misma. Tambi\u00e9n puso de manifiesto que la arquitectura institucional de la uni\u00f3n monetaria europea era muy deficiente. Y a todo ello se uni\u00f3 la aplicaci\u00f3n de pol\u00edticas econ\u00f3micas equivocadas antes y durante la crisis. Como consecuencia de ello, la crisis financiera internacional se transform\u00f3 en la crisis del euro y ello provoc\u00f3 que los pa\u00edses afectados tuvieran que pagar un alto precio en t\u00e9rminos de producci\u00f3n, empleo, endeudamiento, diferencias econ\u00f3micas y fragmentaci\u00f3n pol\u00edtica.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.frdelpino.es\/wp-content\/gallery\/loukas\/loukas-tsoukalis-w14.jpg\" alt=\"La Fundaci\u00c3\u00b3n Rafael del Pino organiza la conferencia magistral &quot;En defensa de Europa, \u00c2\u00bftiene salvaci\u00c3\u00b3n el proyecto Europeo?&quot; de Loukas Tsoukalis. En Madrid el 16 de junio de 2016. DS\" width=\"255\" height=\"170\" \/>A su vez, la crisis de los refugiados sac\u00f3 a la luz las profundas diferencias que separan a los pa\u00edses de la Uni\u00f3n Europea de sus vecinos del este e, incluso, a la parte Occidental de la UE de su parte Oriental. Muchos de estos pa\u00edses son perdedores en el proceso de globalizaci\u00f3n y son dirigidos por gobiernos corruptos, lo que dificulta la salida de esa situaci\u00f3n. En este contexto se produjeron dos acontecimientos fundamentales: la primavera \u00e1rabe, que desestabiliz\u00f3 Oriente Medio y el norte de \u00c1frica y, de una u otra forma, dio origen a las oleadas de inmigrantes y refugiados de los \u00faltimos a\u00f1os, y el desaf\u00edo de Rusia a la \u201cpax europea\u201d, alentando la llegada de refugiados, interviniendo en los procesos pol\u00edticos europeos, etc.<\/p>\n<p style=\"text-align: justify;\">Estas dos crisis son, de por s\u00ed, enormes y sus consecuencias han reducido el apoyo de la poblaci\u00f3n a Europa. Adem\u00e1s, sus efectos han coincidido en el tiempo con una crisis institucional de la propia Uni\u00f3n Europea, que se ha derivado de una expansi\u00f3n continua del proyecto europeo, sin pararse en ning\u00fan momento a fortalecer y consolidar lo que ya se hab\u00eda conseguido antes de seguir avanzando en la inclusi\u00f3n de nuevos pa\u00edses. El resultado ha sido la creaci\u00f3n de un centro d\u00e9bil en la UE.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n hay que tener en cuenta que estas crisis que han castigado a la Uni\u00f3n Europea se han producido con la globalizaci\u00f3n como tel\u00f3n de fondo. Y la globalizaci\u00f3n ha generado divisiones entre los ganadores y los perdedores que ha provocado. En este escenario, las sociedades han confundido las restricciones que se derivan de la globalizaci\u00f3n con aquellas otras que impone la UE. Y los gobiernos europeos, que suelen utilizar la excusa del imperativo comunitario para eludir sus responsabilidades, han convertido al proyecto europeo en cabeza de turco de los problemas que han creado esos mismos gobiernos o que se derivan de la globalizaci\u00f3n. Eso ha alimentado la percepci\u00f3n de la Uni\u00f3n Europea como un elemento de divisi\u00f3n, como algo cada vez m\u00e1s grande, m\u00e1s intrusivo y menos inclusivo, en un contexto de crecimiento econ\u00f3mico lento y creciente desigualdad.<\/p>\n<p style=\"text-align: justify;\">Europa, por tanto, no se ha visto dividida por la crisis del euro o por el problema de los inmigrantes y los refugiados. Las fracturas ya llevaban tiempo ah\u00ed, aunque sin aflorar a la superficie; estas crisis solo las han mostrado claramente y las han ampliado.<\/p>\n<p style=\"text-align: justify;\">En este contexto, es l\u00f3gico que el apoyo de los ciudadanos al proyecto de construcci\u00f3n europea se encuentre en m\u00ednimos hist\u00f3ricos. A pesar de ello, no apuestan por la ruptura, salvo los brit\u00e1nicos, porque temen las consecuencias de la desintegraci\u00f3n. Adem\u00e1s, muchos de ellos tampoco conf\u00edan en las \u00e9lites pol\u00edticas tradicionales y pasan a apoyar opciones populistas, lo que revela la necesidad de entender las causas del descontento de la poblaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00bfC\u00f3mo se resuelve el problema europeo? Evidentemente, la soluci\u00f3n no es sencilla. Por el contrario, pasa por tomar decisiones dif\u00edciles y preguntarse cu\u00e1nta soberan\u00eda se comparte y para qu\u00e9, esto es, qu\u00e9 \u00e1mbitos o pol\u00edticas tienen que estar en manos europeas y qu\u00e9 se pretende conseguir con ellas. Tambi\u00e9n es preciso analizar si hay una relaci\u00f3n entre competitividad econ\u00f3mica y desigualdad e, incluso, hay que considerar si se establecen restricciones a la libertad de circulaci\u00f3n de los trabajadores, comenta Tsoukalis. Y, por supuesto, hay que resolver el problema del d\u00e9ficit democr\u00e1tico de las instituciones europeas.<\/p>\n<p style=\"text-align: justify;\">En cuanto al euro, Tsoukalis reconoce que la moneda \u00fanica fue un gran error, al menos tal y como se dise\u00f1\u00f3. Ahora bien, ser\u00eda una equivocaci\u00f3n a\u00fan mayor abandonarlo.<\/p>\n<p style=\"text-align: justify;\">La cuesti\u00f3n, en \u00faltima instancia, no es si queremos m\u00e1s o menos Europa. La cuesti\u00f3n es qu\u00e9 tipo de Europa queremos.<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.frdelpino.es\/video\/defensa-europa-salvacion-proyecto-europeo\/\"><strong>Acceda a la conferencia completa<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Europea no pasa, precisamente, por los mejores momentos de su historia. Aquellos momentos de euforia que se vivieron cuando se puso en marcha el euro, la UE se ampli\u00f3 a los pa\u00edses del este y se trabajaba por un proyecto de constituci\u00f3n europea, hoy han quedado atr\u00e1s y han dado paso a un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[105,35,94,36,63],"class_list":["post-1590","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia_y_empresa","tag-euro","tag-geopolitica","tag-globalizacion","tag-gobernanza","tag-relaciones-internacionales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Uni\u00f3n Europea en entredicho - FRP Gaceta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Uni\u00f3n Europea en entredicho - FRP Gaceta\" \/>\n<meta property=\"og:description\" content=\"La Uni\u00f3n Europea no pasa, precisamente, por los mejores momentos de su historia. Aquellos momentos de euforia que se vivieron cuando se puso en marcha el euro, la UE se ampli\u00f3 a los pa\u00edses del este y se trabajaba por un proyecto de constituci\u00f3n europea, hoy han quedado atr\u00e1s y han dado paso a un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/\" \/>\n<meta property=\"og:site_name\" content=\"FRP Gaceta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frdelpino\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-02T10:55:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-29T10:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/07\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlota Taboada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frdelpino\" \/>\n<meta name=\"twitter:site\" content=\"@frdelpino\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlota Taboada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/\"},\"author\":{\"name\":\"Carlota Taboada\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\"},\"headline\":\"La Uni\u00f3n Europea en entredicho\",\"datePublished\":\"2018-01-02T10:55:11+00:00\",\"dateModified\":\"2023-12-29T10:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/\"},\"wordCount\":983,\"image\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg\",\"keywords\":[\"euro\",\"geopol\u00edtica\",\"Globalizaci\u00f3n\",\"gobernanza\",\"relaciones internacionales\"],\"articleSection\":[\"Econom\u00eda y empresa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/\",\"name\":\"La Uni\u00f3n Europea en entredicho - FRP Gaceta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg\",\"datePublished\":\"2018-01-02T10:55:11+00:00\",\"dateModified\":\"2023-12-29T10:14:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg\",\"contentUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/union-europea-crisis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Uni\u00f3n Europea en entredicho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\",\"name\":\"FRP Gaceta\",\"description\":\"Una iniciativa de la Fundaci\u00f3n Rafael del Pino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\",\"name\":\"Carlota Taboada\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/author\\\/ctaboada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Uni\u00f3n Europea en entredicho - FRP Gaceta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/","og_locale":"es_ES","og_type":"article","og_title":"La Uni\u00f3n Europea en entredicho - FRP Gaceta","og_description":"La Uni\u00f3n Europea no pasa, precisamente, por los mejores momentos de su historia. Aquellos momentos de euforia que se vivieron cuando se puso en marcha el euro, la UE se ampli\u00f3 a los pa\u00edses del este y se trabajaba por un proyecto de constituci\u00f3n europea, hoy han quedado atr\u00e1s y han dado paso a un [&hellip;]","og_url":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/","og_site_name":"FRP Gaceta","article_publisher":"https:\/\/www.facebook.com\/frdelpino","article_published_time":"2018-01-02T10:55:11+00:00","article_modified_time":"2023-12-29T10:14:11+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/07\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg","type":"image\/jpeg"}],"author":"Carlota Taboada","twitter_card":"summary_large_image","twitter_creator":"@frdelpino","twitter_site":"@frdelpino","twitter_misc":{"Escrito por":"Carlota Taboada","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#article","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/"},"author":{"name":"Carlota Taboada","@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86"},"headline":"La Uni\u00f3n Europea en entredicho","datePublished":"2018-01-02T10:55:11+00:00","dateModified":"2023-12-29T10:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/"},"wordCount":983,"image":{"@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#primaryimage"},"thumbnailUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/07\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg","keywords":["euro","geopol\u00edtica","Globalizaci\u00f3n","gobernanza","relaciones internacionales"],"articleSection":["Econom\u00eda y empresa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/","url":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/","name":"La Uni\u00f3n Europea en entredicho - FRP Gaceta","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#primaryimage"},"image":{"@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#primaryimage"},"thumbnailUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/07\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg","datePublished":"2018-01-02T10:55:11+00:00","dateModified":"2023-12-29T10:14:11+00:00","author":{"@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86"},"breadcrumb":{"@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#primaryimage","url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/07\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg","contentUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/07\/wing-europe-flag-weapon-parliament-flags-738738-pxhere.com_-e1530528787931.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/frdelpino.es\/actualidad\/union-europea-crisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/frdelpino.es\/actualidad\/"},{"@type":"ListItem","position":2,"name":"La Uni\u00f3n Europea en entredicho"}]},{"@type":"WebSite","@id":"https:\/\/frdelpino.es\/actualidad\/#website","url":"https:\/\/frdelpino.es\/actualidad\/","name":"FRP Gaceta","description":"Una iniciativa de la Fundaci\u00f3n Rafael del Pino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frdelpino.es\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86","name":"Carlota Taboada","url":"https:\/\/frdelpino.es\/actualidad\/author\/ctaboada\/"}]}},"_links":{"self":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/comments?post=1590"}],"version-history":[{"count":2,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1590\/revisions"}],"predecessor-version":[{"id":1593,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1590\/revisions\/1593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/media\/1591"}],"wp:attachment":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/media?parent=1590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/categories?post=1590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/tags?post=1590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}