{"id":1790,"date":"2018-11-26T12:30:30","date_gmt":"2018-11-26T10:30:30","guid":{"rendered":"https:\/\/frdelpino.es\/try\/actualidad\/?p=1790"},"modified":"2023-12-29T12:15:52","modified_gmt":"2023-12-29T10:15:52","slug":"banca-comercio-y-una-moneda-unica","status":"publish","type":"post","link":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/","title":{"rendered":"Banca, comercio y una moneda \u00fanica"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Gita Gopinath<\/strong><\/span>, John Zwaanstra Professor de Estudios Internacionales y de Econ\u00f3micas en la Universidad de Harvard,\u00a0particip\u00f3 en la X edici\u00f3n del\u00a0<em>Workshop in International Economics<\/em>, celebrado del 17 al 20 de septiembre en Boston, con su presentaci\u00f3n\u00a0<em>Banca, comercio y una moneda \u00fanica<\/em>.<\/p>\n<p style=\"text-align: justify;\">Gopinath (2017) replantea el modelo de Mundell-Fleming (M-F) para una econom\u00eda peque\u00f1a y abierta. Un supuesto clave del modelo M-F es que los precios son r\u00edgidos en la divisa del productor. As\u00ed, como la evoluci\u00f3n de los t\u00e9rminos de comercio depende exclusivamente de la evoluci\u00f3n del tipo de cambio, si la demanda de d\u00f3lares disminuye, el d\u00f3lar se deprecia frente al resto de monedas del mundo, mejorando los t\u00e9rminos de comercio y el saldo de la cuenta corriente estadounidense.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, se observa que el volumen de comercio denominado en d\u00f3lares en el mundo excede el volumen de comercio que lleva a cabo EE.UU., lo cual sugiere que otros pa\u00edses emplean el d\u00f3lar como moneda vehicular para llevar a cabo sus transacciones comerciales con pa\u00edses distintos de EE.UU. Este tambi\u00e9n es el caso de Espa\u00f1a, donde el 54% de las importaciones y el 58% de las exportaciones est\u00e1n denominadas en d\u00f3lares.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p>El volumen de comercio denominado en d\u00f3lares en el mundo excede el volumen de comercio que lleva a cabo EE.UU., lo cual sugiere que otros pa\u00edses emplean el d\u00f3lar como moneda vehicular para llevar a cabo sus transacciones comerciales con pa\u00edses distintos de EE.UU.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Gopinath (2017) replantea el supuesto de M-F al suponer que todo el comercio mundial se denomina en una divisa dominante como el d\u00f3lar. El nuevo <em>Dominant Currency Paradigm<\/em> (DCP) predice que, si una econom\u00eda importa inputs denominados en d\u00f3lares, al producirse una apreciaci\u00f3n del d\u00f3lar respecto a la moneda local, los t\u00e9rminos de comercio permanecer\u00e1n estables pero el precio de los inputs importados aumentar\u00e1, por lo que disminuir\u00e1n las importaciones denominadas en d\u00f3lares hacia esa econom\u00eda procedentes de cualquier pa\u00eds. Por otro lado, las exportaciones a EE.UU. no mejorar\u00e1n (la depreciaci\u00f3n de la moneda local respecto al d\u00f3lar se compensa con el aumento del precio de los inputs importados denominados en d\u00f3lares), mientras que el impacto sobre las exportaciones a otros destinos distintos de los EE.UU. depender\u00e1 de la evoluci\u00f3n del tipo de cambio de la moneda local del otro pa\u00eds respecto del d\u00f3lar.<\/p>\n<p style=\"text-align: justify;\">De esta manera, Gita Gopinath demuestra c\u00f3mo <strong>la depreciaci\u00f3n de las monedas de los emergentes respecto al d\u00f3lar est\u00e1 asociada con una desaceleraci\u00f3n del comercio global<\/strong>.<\/p>\n<figure id=\"attachment_2100\" aria-describedby=\"caption-attachment-2100\" style=\"width: 125px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2100\" title=\"Gita Gopinath\" src=\"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/11\/97px-Gita_Gopinath_at_the_World_Economic_Forum_on_India_2012.jpg\" alt=\"https:\/\/commons.wikimedia.org\/w\/index.php?curid=22578833\" width=\"125\" height=\"187\" \/><figcaption id=\"caption-attachment-2100\" class=\"wp-caption-text\">By World Economic Forum from Cologny, Switzerland &#8211; Rebooting India, CC BY-SA 2.0<\/figcaption><\/figure>\n<p>Por otro lado, Gopinath (2018) se plantea c\u00f3mo llega a ser dominante una divisa. Seg\u00fan el modelo de Gopinath (2018), <strong>una divisa se convierte en divisa dominante a partir de una proporci\u00f3n determinada de transacciones comerciales denominadas en dicha divisa<\/strong>. A partir de este umbral, la banca comercial comienza a producir pasivos denominados en dicha divisa, mientras que sus activos, los cr\u00e9ditos concedidos para la financiaci\u00f3n de proyectos locales, siguen denominados en moneda local. Ello genera un <em>mismatch<\/em> de divisas en los balances de la banca local que puede ser fuente de inestabilidad financiera en caso de materializarse el riesgo de tipo de cambio por, por ejemplo, una subida de los tipos de inter\u00e9s por parte del banco central emisor de la divisa dominante.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Se produce as\u00ed un c\u00edrculo vicioso: m\u00e1s volumen de comercio denominado en d\u00f3lares redunda en un mayor gasto en d\u00f3lares y en mayor demanda de activos seguros denominados en d\u00f3lares, lo cual reduce el tipo de inter\u00e9s exigido por los inversores por la tenencia de estos activos, lo cual incentiva a denominar las transacciones comerciales en d\u00f3lares. Este menor tipo de inter\u00e9s pagado por los activos seguros denominados en d\u00f3lares respecto del pagado por los activos seguros denominados en otras divisas es el denominado <em>privilegio exorbitante <\/em>de la divisa dominante.<\/p>\n<p style=\"text-align: justify;\">Gopinath (2018) recuerda las palabras de Eichengreen (2010) sobre el procedimiento para internacionalizar una divisa, quien sugiere que \u201cla secuencia l\u00f3gica consiste, en primer lugar, en fomentar su uso en transacciones comerciales; en segundo lugar, en incentivar su uso en transacciones financieras; y finalmente, en favorecer la utilizaci\u00f3n de la divisa por bancos centrales y gobiernos como dep\u00f3sito de valor de sus reservas\u201d.<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo, Gopinath (2017) entra en el debate que se produce durante 2017 sobre la reforma del impuesto sobre sociedades en los EE.UU. Explica que la aplicaci\u00f3n de un impuesto con ajustes en frontera equivaldr\u00eda, de facto, a la combinaci\u00f3n de un arancel sobre las importaciones y de una subvenci\u00f3n sobre las exportaciones. Argumenta que ello producir\u00eda distorsiones en los precios relativos y que tendr\u00eda un impacto sobre el comercio internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gita Gopinath, John Zwaanstra Professor de Estudios Internacionales y de Econ\u00f3micas en la Universidad de Harvard,\u00a0particip\u00f3 en la X edici\u00f3n del\u00a0Workshop in International Economics, celebrado del 17 al 20 de septiembre en Boston, con su presentaci\u00f3n\u00a0Banca, comercio y una moneda \u00fanica. Gopinath (2017) replantea el modelo de Mundell-Fleming (M-F) para una econom\u00eda peque\u00f1a y abierta. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[131,143,145,144],"class_list":{"0":"post-1790","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-economia_y_empresa","8":"tag-banca","9":"tag-comercio","10":"tag-ecomomia","11":"tag-moneda-unica","12":"post_format-post-format-video"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banca, comercio y una moneda \u00fanica - FRP Gaceta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banca, comercio y una moneda \u00fanica - FRP Gaceta\" \/>\n<meta property=\"og:description\" content=\"Gita Gopinath, John Zwaanstra Professor de Estudios Internacionales y de Econ\u00f3micas en la Universidad de Harvard,\u00a0particip\u00f3 en la X edici\u00f3n del\u00a0Workshop in International Economics, celebrado del 17 al 20 de septiembre en Boston, con su presentaci\u00f3n\u00a0Banca, comercio y una moneda \u00fanica. Gopinath (2017) replantea el modelo de Mundell-Fleming (M-F) para una econom\u00eda peque\u00f1a y abierta. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/\" \/>\n<meta property=\"og:site_name\" content=\"FRP Gaceta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frdelpino\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-26T10:30:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-29T10:15:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/10\/100-abundance-achievement-730564-e1538733186250.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlota Taboada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frdelpino\" \/>\n<meta name=\"twitter:site\" content=\"@frdelpino\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlota Taboada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/\"},\"author\":{\"name\":\"Carlota Taboada\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\"},\"headline\":\"Banca, comercio y una moneda \u00fanica\",\"datePublished\":\"2018-11-26T10:30:30+00:00\",\"dateModified\":\"2023-12-29T10:15:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/\"},\"wordCount\":848,\"image\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/100-abundance-achievement-730564-e1538733186250.jpg\",\"keywords\":[\"banca\",\"comercio\",\"ecomom\u00eda\",\"moneda \u00fanica\"],\"articleSection\":[\"Econom\u00eda y empresa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/\",\"name\":\"Banca, comercio y una moneda \u00fanica - FRP Gaceta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/100-abundance-achievement-730564-e1538733186250.jpg\",\"datePublished\":\"2018-11-26T10:30:30+00:00\",\"dateModified\":\"2023-12-29T10:15:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/100-abundance-achievement-730564-e1538733186250.jpg\",\"contentUrl\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/100-abundance-achievement-730564-e1538733186250.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/banca-comercio-y-una-moneda-unica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banca, comercio y una moneda \u00fanica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\",\"name\":\"FRP Gaceta\",\"description\":\"Una iniciativa de la Fundaci\u00f3n Rafael del Pino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#\\\/schema\\\/person\\\/5b3e77df61158f3160fedebdf5407d86\",\"name\":\"Carlota Taboada\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/author\\\/ctaboada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banca, comercio y una moneda \u00fanica - FRP Gaceta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/","og_locale":"es_ES","og_type":"article","og_title":"Banca, comercio y una moneda \u00fanica - FRP Gaceta","og_description":"Gita Gopinath, John Zwaanstra Professor de Estudios Internacionales y de Econ\u00f3micas en la Universidad de Harvard,\u00a0particip\u00f3 en la X edici\u00f3n del\u00a0Workshop in International Economics, celebrado del 17 al 20 de septiembre en Boston, con su presentaci\u00f3n\u00a0Banca, comercio y una moneda \u00fanica. Gopinath (2017) replantea el modelo de Mundell-Fleming (M-F) para una econom\u00eda peque\u00f1a y abierta. [&hellip;]","og_url":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/","og_site_name":"FRP Gaceta","article_publisher":"https:\/\/www.facebook.com\/frdelpino","article_published_time":"2018-11-26T10:30:30+00:00","article_modified_time":"2023-12-29T10:15:52+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/10\/100-abundance-achievement-730564-e1538733186250.jpg","type":"image\/jpeg"}],"author":"Carlota Taboada","twitter_card":"summary_large_image","twitter_creator":"@frdelpino","twitter_site":"@frdelpino","twitter_misc":{"Escrito por":"Carlota Taboada","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#article","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/"},"author":{"name":"Carlota Taboada","@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86"},"headline":"Banca, comercio y una moneda \u00fanica","datePublished":"2018-11-26T10:30:30+00:00","dateModified":"2023-12-29T10:15:52+00:00","mainEntityOfPage":{"@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/"},"wordCount":848,"image":{"@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#primaryimage"},"thumbnailUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/10\/100-abundance-achievement-730564-e1538733186250.jpg","keywords":["banca","comercio","ecomom\u00eda","moneda \u00fanica"],"articleSection":["Econom\u00eda y empresa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/","url":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/","name":"Banca, comercio y una moneda \u00fanica - FRP Gaceta","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#primaryimage"},"image":{"@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#primaryimage"},"thumbnailUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/10\/100-abundance-achievement-730564-e1538733186250.jpg","datePublished":"2018-11-26T10:30:30+00:00","dateModified":"2023-12-29T10:15:52+00:00","author":{"@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86"},"breadcrumb":{"@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#primaryimage","url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/10\/100-abundance-achievement-730564-e1538733186250.jpg","contentUrl":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/10\/100-abundance-achievement-730564-e1538733186250.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/frdelpino.es\/actualidad\/banca-comercio-y-una-moneda-unica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/frdelpino.es\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Banca, comercio y una moneda \u00fanica"}]},{"@type":"WebSite","@id":"https:\/\/frdelpino.es\/actualidad\/#website","url":"https:\/\/frdelpino.es\/actualidad\/","name":"FRP Gaceta","description":"Una iniciativa de la Fundaci\u00f3n Rafael del Pino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frdelpino.es\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/frdelpino.es\/actualidad\/#\/schema\/person\/5b3e77df61158f3160fedebdf5407d86","name":"Carlota Taboada","url":"https:\/\/frdelpino.es\/actualidad\/author\/ctaboada\/"}]}},"_links":{"self":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/comments?post=1790"}],"version-history":[{"count":12,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1790\/revisions"}],"predecessor-version":[{"id":2121,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts\/1790\/revisions\/2121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/media\/1840"}],"wp:attachment":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/media?parent=1790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/categories?post=1790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/tags?post=1790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}