{"id":204,"count":1,"description":"","link":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/","name":"presupuesto","slug":"presupuesto","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>presupuesto archivos - FRP Gaceta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"presupuesto archivos - FRP Gaceta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/\" \/>\n<meta property=\"og:site_name\" content=\"FRP Gaceta\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/02\/foto_palacio_cabecera2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@frdelpino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/tag\\\/presupuesto\\\/\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/tag\\\/presupuesto\\\/\",\"name\":\"presupuesto archivos - FRP Gaceta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/tag\\\/presupuesto\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/tag\\\/presupuesto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"presupuesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/\",\"name\":\"FRP Gaceta\",\"description\":\"Una iniciativa de la Fundaci\u00f3n Rafael del Pino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frdelpino.es\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"presupuesto archivos - FRP Gaceta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/","og_locale":"es_ES","og_type":"article","og_title":"presupuesto archivos - FRP Gaceta","og_url":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/","og_site_name":"FRP Gaceta","og_image":[{"width":1920,"height":920,"url":"https:\/\/frdelpino.es\/actualidad\/wp-content\/uploads\/2018\/02\/foto_palacio_cabecera2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@frdelpino","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/","url":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/","name":"presupuesto archivos - FRP Gaceta","isPartOf":{"@id":"https:\/\/frdelpino.es\/actualidad\/#website"},"breadcrumb":{"@id":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/frdelpino.es\/actualidad\/tag\/presupuesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/frdelpino.es\/actualidad\/"},{"@type":"ListItem","position":2,"name":"presupuesto"}]},{"@type":"WebSite","@id":"https:\/\/frdelpino.es\/actualidad\/#website","url":"https:\/\/frdelpino.es\/actualidad\/","name":"FRP Gaceta","description":"Una iniciativa de la Fundaci\u00f3n Rafael del Pino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frdelpino.es\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/tags\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/frdelpino.es\/actualidad\/wp-json\/wp\/v2\/posts?tags=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}